{"id":4542,"date":"2025-09-27T06:39:20","date_gmt":"2025-09-27T05:39:20","guid":{"rendered":"https:\/\/www.guanfeng.co.uk\/?post_type=product&#038;p=4542"},"modified":"2025-09-27T06:39:21","modified_gmt":"2025-09-27T05:39:21","slug":"multi-material-phone-holder-130mm-non-slip-base-21-32cm-telescopic","status":"publish","type":"product","link":"https:\/\/www.guanfeng.co.uk\/index.php\/product\/multi-material-phone-holder-130mm-non-slip-base-21-32cm-telescopic\/","title":{"rendered":"Multi-Material Phone Holder, 130mm Non-Slip Base, 21-32cm Telescopic"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-4550\" src=\"https:\/\/www.dollyschoice.com\/wp-content\/uploads\/2025\/09\/863-6-300x273.png\" alt=\"\" width=\"1327\" height=\"1208\" srcset=\"https:\/\/www.guanfeng.co.uk\/wp-content\/uploads\/2025\/09\/863-6-300x273.png 300w, https:\/\/www.guanfeng.co.uk\/wp-content\/uploads\/2025\/09\/863-6-600x545.png 600w, https:\/\/www.guanfeng.co.uk\/wp-content\/uploads\/2025\/09\/863-6.png 742w\" sizes=\"auto, (max-width: 1327px) 100vw, 1327px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4547,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"product_brand":[],"product_cat":[45],"product_tag":[],"class_list":["post-4542","product","type-product","status-publish","has-post-thumbnail","product_cat-mobile-phone-accessories","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-single-variable","ast-product-tabs-layout-horizontal","ast-qv-on-image","first","instock","shipping-taxable","purchasable","product-type-variable"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/product\/4542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/comments?post=4542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/media\/4547"}],"wp:attachment":[{"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/media?parent=4542"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/product_brand?post=4542"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/product_cat?post=4542"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.guanfeng.co.uk\/index.php\/wp-json\/wp\/v2\/product_tag?post=4542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}